{"id":355,"count":29,"description":"El Guzer\u00e1 se adapta f\u00e1cilmente a medios adversos, y posee una gran capacidad de crecimiento en pastoreo. Adem\u00e1s de ser un buen productor de carne, por selecci\u00f3n ha demostrado ser tambi\u00e9n una raza productora de leche, por sus grandes cualidades le garantizan un lugar de predominancia en la ganader\u00eda tropical.","link":"https:\/\/geneticatricolor.com\/home\/categoria-producto\/venta-de-semen\/razas-lecheras-tropico\/semen-guzerat-leche\/","name":"Guzerat Lechero","slug":"semen-guzerat-leche","taxonomy":"product_cat","parent":230,"meta":[],"menu_order":50,"acf":[],"_links":{"self":[{"href":"https:\/\/geneticatricolor.com\/home\/wp-json\/wp\/v2\/product_cat\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/geneticatricolor.com\/home\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/geneticatricolor.com\/home\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/geneticatricolor.com\/home\/wp-json\/wp\/v2\/product_cat\/230"}],"wp:post_type":[{"href":"https:\/\/geneticatricolor.com\/home\/wp-json\/wp\/v2\/product?product_cat=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}